{"id":60159,"date":"2025-04-25T16:49:01","date_gmt":"2025-04-25T16:49:01","guid":{"rendered":"https:\/\/www.infopiniones.com\/colombia\/2020\/09\/05\/compania-pesquera-de-langostinos-ltda\/"},"modified":"2025-04-25T16:49:01","modified_gmt":"2025-04-25T16:49:01","slug":"compania-pesquera-de-langostinos-ltda","status":"publish","type":"post","link":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/","title":{"rendered":"Compa\u00f1ia Pesquera De Langostinos Ltda"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[223,224],"tags":[],"class_list":["post-60159","post","type-post","status-publish","format-standard","hentry","category-buenaventura","category-valle-del-cauca-buenaventura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/\" \/>\n<meta property=\"og:site_name\" content=\"Opiniones de empresas e instituciones de Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-25T16:49:01+00:00\" \/>\n<meta name=\"author\" content=\"infopiniones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"infopiniones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/\"},\"author\":{\"name\":\"infopiniones\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/person\\\/5adeaae6142e5d5d25b5060f2ba4c48e\"},\"headline\":\"Compa\u00f1ia Pesquera De Langostinos Ltda\",\"datePublished\":\"2025-04-25T16:49:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/\"},\"wordCount\":6,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\"},\"articleSection\":[\"Buenaventura\",\"Valle Del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/\",\"name\":\"Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#website\"},\"datePublished\":\"2025-04-25T16:49:01+00:00\",\"description\":\"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/compania-pesquera-de-langostinos-ltda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Opiniones de empresas de Colombia\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/hestia-front\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buenaventura\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valle Del Cauca\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/buenaventura\\\/valle-del-cauca-buenaventura\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Compa\u00f1ia Pesquera De Langostinos Ltda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#website\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/\",\"name\":\"Opiniones de empresas e instituciones de Colombia\",\"description\":\"Opiniones de empresas de Colombia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\",\"name\":\"Opiniones de empresas e instituciones de Colombia\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-infopiniones.png\",\"contentUrl\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-infopiniones.png\",\"width\":275,\"height\":53,\"caption\":\"Opiniones de empresas e instituciones de Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/person\\\/5adeaae6142e5d5d25b5060f2ba4c48e\",\"name\":\"infopiniones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"contentUrl\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"caption\":\"infopiniones\"},\"sameAs\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\"],\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/author\\\/infopiniones\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones","description":"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/","og_locale":"es_ES","og_type":"article","og_title":"Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones","og_description":"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda","og_url":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/","og_site_name":"Opiniones de empresas e instituciones de Colombia","article_published_time":"2025-04-25T16:49:01+00:00","author":"infopiniones","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"infopiniones"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/#article","isPartOf":{"@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/"},"author":{"name":"infopiniones","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/person\/5adeaae6142e5d5d25b5060f2ba4c48e"},"headline":"Compa\u00f1ia Pesquera De Langostinos Ltda","datePublished":"2025-04-25T16:49:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/"},"wordCount":6,"commentCount":0,"publisher":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#organization"},"articleSection":["Buenaventura","Valle Del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/","url":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/","name":"Compa\u00f1ia Pesquera De Langostinos Ltda | Informaci\u00f3n y opiniones","isPartOf":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#website"},"datePublished":"2025-04-25T16:49:01+00:00","description":"Informaci\u00f3n y opiniones sobre Compa\u00f1ia Pesquera De Langostinos Ltda","breadcrumb":{"@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/compania-pesquera-de-langostinos-ltda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Opiniones de empresas de Colombia","item":"https:\/\/www.infopiniones.com\/colombia\/hestia-front\/"},{"@type":"ListItem","position":2,"name":"Buenaventura","item":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/"},{"@type":"ListItem","position":3,"name":"Valle Del Cauca","item":"https:\/\/www.infopiniones.com\/colombia\/buenaventura\/valle-del-cauca-buenaventura\/"},{"@type":"ListItem","position":4,"name":"Compa\u00f1ia Pesquera De Langostinos Ltda"}]},{"@type":"WebSite","@id":"https:\/\/www.infopiniones.com\/colombia\/#website","url":"https:\/\/www.infopiniones.com\/colombia\/","name":"Opiniones de empresas e instituciones de Colombia","description":"Opiniones de empresas de Colombia","publisher":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infopiniones.com\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.infopiniones.com\/colombia\/#organization","name":"Opiniones de empresas e instituciones de Colombia","url":"https:\/\/www.infopiniones.com\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/uploads\/2020\/12\/logo-infopiniones.png","contentUrl":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/uploads\/2020\/12\/logo-infopiniones.png","width":275,"height":53,"caption":"Opiniones de empresas e instituciones de Colombia"},"image":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/person\/5adeaae6142e5d5d25b5060f2ba4c48e","name":"infopiniones","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","url":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","contentUrl":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","caption":"infopiniones"},"sameAs":["https:\/\/www.infopiniones.com\/colombia"],"url":"https:\/\/www.infopiniones.com\/colombia\/author\/infopiniones\/"}]}},"_links":{"self":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts\/60159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/comments?post=60159"}],"version-history":[{"count":0,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts\/60159\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/media?parent=60159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/categories?post=60159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/tags?post=60159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}