{"id":67813,"date":"2020-10-06T00:11:57","date_gmt":"2020-10-06T00:11:57","guid":{"rendered":"https:\/\/www.infopiniones.com\/colombia\/2020\/10\/06\/inversiones-agropecuarias-eja-s-a\/"},"modified":"2020-10-06T00:11:57","modified_gmt":"2020-10-06T00:11:57","slug":"inversiones-agropecuarias-eja-s-a","status":"publish","type":"post","link":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/","title":{"rendered":"Inversiones Agropecuarias  Eja S.A."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[675,676],"tags":[],"class_list":["post-67813","post","type-post","status-publish","format-standard","hentry","category-bugalagrande","category-valle-del-cauca-bugalagrande"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Opiniones de empresas e instituciones de Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T00:11:57+00:00\" \/>\n<meta name=\"author\" content=\"infopiniones\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"infopiniones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/\"},\"author\":{\"name\":\"infopiniones\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/person\\\/5adeaae6142e5d5d25b5060f2ba4c48e\"},\"headline\":\"Inversiones Agropecuarias Eja S.A.\",\"datePublished\":\"2020-10-06T00:11:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/\"},\"wordCount\":5,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\"},\"articleSection\":[\"Bugalagrande\",\"Valle Del Cauca\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/\",\"name\":\"Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#website\"},\"datePublished\":\"2020-10-06T00:11:57+00:00\",\"description\":\"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/inversiones-agropecuarias-eja-s-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Opiniones de empresas de Colombia\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/hestia-front\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bugalagrande\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valle Del Cauca\",\"item\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/bugalagrande\\\/valle-del-cauca-bugalagrande\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Inversiones Agropecuarias Eja S.A.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#website\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/\",\"name\":\"Opiniones de empresas e instituciones de Colombia\",\"description\":\"Opiniones de empresas de Colombia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#organization\",\"name\":\"Opiniones de empresas e instituciones de Colombia\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-infopiniones.png\",\"contentUrl\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo-infopiniones.png\",\"width\":275,\"height\":53,\"caption\":\"Opiniones de empresas e instituciones de Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/#\\\/schema\\\/person\\\/5adeaae6142e5d5d25b5060f2ba4c48e\",\"name\":\"infopiniones\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"contentUrl\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/wp-content\\\/litespeed\\\/avatar\\\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150\",\"caption\":\"infopiniones\"},\"sameAs\":[\"https:\\\/\\\/www.infopiniones.com\\\/colombia\"],\"url\":\"https:\\\/\\\/www.infopiniones.com\\\/colombia\\\/author\\\/infopiniones\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones","description":"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/","og_locale":"es_ES","og_type":"article","og_title":"Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones","og_description":"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.","og_url":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/","og_site_name":"Opiniones de empresas e instituciones de Colombia","article_published_time":"2020-10-06T00:11:57+00:00","author":"infopiniones","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"infopiniones"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/#article","isPartOf":{"@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/"},"author":{"name":"infopiniones","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/person\/5adeaae6142e5d5d25b5060f2ba4c48e"},"headline":"Inversiones Agropecuarias Eja S.A.","datePublished":"2020-10-06T00:11:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/"},"wordCount":5,"commentCount":0,"publisher":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#organization"},"articleSection":["Bugalagrande","Valle Del Cauca"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/","url":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/","name":"Inversiones Agropecuarias Eja S.A. | Informaci\u00f3n y opiniones","isPartOf":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#website"},"datePublished":"2020-10-06T00:11:57+00:00","description":"Informaci\u00f3n y opiniones sobre Inversiones Agropecuarias Eja S.A.","breadcrumb":{"@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/inversiones-agropecuarias-eja-s-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Opiniones de empresas de Colombia","item":"https:\/\/www.infopiniones.com\/colombia\/hestia-front\/"},{"@type":"ListItem","position":2,"name":"Bugalagrande","item":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/"},{"@type":"ListItem","position":3,"name":"Valle Del Cauca","item":"https:\/\/www.infopiniones.com\/colombia\/bugalagrande\/valle-del-cauca-bugalagrande\/"},{"@type":"ListItem","position":4,"name":"Inversiones Agropecuarias Eja S.A."}]},{"@type":"WebSite","@id":"https:\/\/www.infopiniones.com\/colombia\/#website","url":"https:\/\/www.infopiniones.com\/colombia\/","name":"Opiniones de empresas e instituciones de Colombia","description":"Opiniones de empresas de Colombia","publisher":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.infopiniones.com\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.infopiniones.com\/colombia\/#organization","name":"Opiniones de empresas e instituciones de Colombia","url":"https:\/\/www.infopiniones.com\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/uploads\/2020\/12\/logo-infopiniones.png","contentUrl":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/uploads\/2020\/12\/logo-infopiniones.png","width":275,"height":53,"caption":"Opiniones de empresas e instituciones de Colombia"},"image":{"@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.infopiniones.com\/colombia\/#\/schema\/person\/5adeaae6142e5d5d25b5060f2ba4c48e","name":"infopiniones","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","url":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","contentUrl":"https:\/\/www.infopiniones.com\/colombia\/wp-content\/litespeed\/avatar\/8e808f6f9dce08f95aafa7ab4f60841c.jpg?ver=1778116150","caption":"infopiniones"},"sameAs":["https:\/\/www.infopiniones.com\/colombia"],"url":"https:\/\/www.infopiniones.com\/colombia\/author\/infopiniones\/"}]}},"_links":{"self":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts\/67813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/comments?post=67813"}],"version-history":[{"count":0,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/posts\/67813\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/media?parent=67813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/categories?post=67813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infopiniones.com\/colombia\/wp-json\/wp\/v2\/tags?post=67813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}